{"id":204201,"date":"2026-05-13T11:22:35","date_gmt":"2021-04-28T20:40:42","guid":{"rendered":"https:\/\/adltexas.org\/pets\/circus-46590150\/"},"modified":"2026-05-13T11:22:40","modified_gmt":"2026-05-13T16:22:40","slug":"jones-37463386","status":"publish","type":"pets","link":"https:\/\/adltexas.org\/es\/pets\/jones-37463386\/","title":{"rendered":"Jones"},"content":{"rendered":"<p>Hola, me llamo Jones y soy un perro que ha tenido un comienzo un poco duro. Cuando la gente viene al refugio a visitarme, tiendo a mostrarme terrible en mi perrera, y eso les asusta. Pero d\u00e9jenme decirles que no es porque sea un perro asustadizo, sino porque el refugio tambi\u00e9n me da un poco de miedo y tengo que poner cara de valiente para protegerme de los extra\u00f1os.<\/p>\n<p>Sin embargo, una vez fuera de mi perrera, ver\u00e1s mi verdadero yo. Soy un chico listo, bien educado y muy leal a las personas que quiero. Podr\u00eda decirse que soy como un diamante en bruto, s\u00f3lo necesito que alguien me d\u00e9 una oportunidad y vea m\u00e1s all\u00e1 de mi comportamiento inicial.<\/p>\n<p>Puede que sea un perro adulto, pero a\u00fan tengo mucho amor que dar. Conozco las cuerdas y s\u00f3lo necesito una familia experta en perros que est\u00e9 dispuesta a no juzgarme bas\u00e1ndose en las primeras impresiones. Una vez que te conozca y me sienta seguro, ser\u00e9 tu mejor amigo de por vida.<\/p>\n<p>As\u00ed que si est\u00e1s buscando un compa\u00f1ero leal e inteligente que s\u00f3lo necesite una oportunidad para brillar, por favor, considera la posibilidad de darme una oportunidad, Jones. Te prometo que, con un poco de paciencia y cari\u00f1o, ser\u00e9 el mejor perro que puedas pedir.<\/p>","protected":false},"featured_media":0,"template":"","format":"standard","pet_categories":[22,17,16,21],"cat_breeds":[],"dog_breeds":[438,344],"pet_status":[30,704],"pet_age_filter":[703],"pet_location":[708],"class_list":{"0":"post-204201","1":"pets","2":"type-pets","3":"status-publish","4":"format-standard","6":"pet_categories-pets","7":"pet_categories-dogs","8":"pet_categories-dogs-medium","9":"pet_categories-oldies-but-goodies","10":"dog_breeds-mixed","11":"dog_breeds-shepherd","12":"pet_status-active","13":"pet_status-diamonds-in-the-ruff","14":"pet_age_filter-older-than-6-months","15":"pet_location-nacogdoches-campus"},"acf":{"pet_id":"37463386","sex":"Male","pet_location":"Bldg. 8B","pet_sublocation":"Run 22","pets_image_feed_url":"https:\/\/g.petango.com\/photos\/411\/a8c4881c-ea7b-41f5-8ac2-7ab25a7860e3.jpg","YTVideoID":[],"photo_2":"https:\/\/g.petango.com\/photos\/411\/d4f2096e-ed25-40d5-9478-a3d775078f7f.jpg","photo_3":"https:\/\/g.petango.com\/photos\/411\/24b2e70a-8aad-4305-b76a-1c3f9b369f93.jpg","weight":"49 pounds","birthday":"2016\/12\/24","_dog_primary_breed":[{"term_id":344,"name":"Shepherd","slug":"shepherd","term_group":0,"term_taxonomy_id":373,"taxonomy":"dog_breeds","description":"","parent":0,"count":71,"filter":"raw"},{"term_id":438,"name":"Mixed","slug":"mixed","term_group":0,"term_taxonomy_id":149,"taxonomy":"dog_breeds","description":"","parent":0,"count":189,"filter":"raw"}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jones - Animal Defense League of Texas - San Antonio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adltexas.org\/es\/mascotas\/jones-37463386\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jones - Animal Defense League of Texas - San Antonio\" \/>\n<meta property=\"og:description\" content=\"Hi there, my name is Jones, and I&#039;m a dog who has had a bit of a rough start. When people come to the shelter to visit, I tend to . . .\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adltexas.org\/es\/mascotas\/jones-37463386\/\" \/>\n<meta property=\"og:site_name\" content=\"Animal Defense League of Texas - San Antonio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adltexas\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T16:22:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ADLofTX\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adltexas.org\\\/pets\\\/jones-37463386\\\/\",\"url\":\"https:\\\/\\\/adltexas.org\\\/pets\\\/jones-37463386\\\/\",\"name\":\"Jones - Animal Defense League of Texas - San Antonio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adltexas.org\\\/#website\"},\"datePublished\":\"2021-04-28T20:40:42+00:00\",\"dateModified\":\"2026-05-13T16:22:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adltexas.org\\\/pets\\\/jones-37463386\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adltexas.org\\\/pets\\\/jones-37463386\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adltexas.org\\\/pets\\\/jones-37463386\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adltexas.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pet Posts\",\"item\":\"https:\\\/\\\/adltexas.org\\\/news\\\/pets\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adltexas.org\\\/#website\",\"url\":\"https:\\\/\\\/adltexas.org\\\/\",\"name\":\"Animal Defense League of Texas - San Antonio\",\"description\":\"No Kill Animal Shelter, San Antonio, Texas\",\"publisher\":{\"@id\":\"https:\\\/\\\/adltexas.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adltexas.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adltexas.org\\\/#organization\",\"name\":\"Animal Defense League of Texas\",\"url\":\"https:\\\/\\\/adltexas.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/adltexas.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/adltexas.org\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/adl-logo-ty.gif?fit=140%2C140&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/adltexas.org\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/adl-logo-ty.gif?fit=140%2C140&ssl=1\",\"width\":140,\"height\":140,\"caption\":\"Animal Defense League of Texas\"},\"image\":{\"@id\":\"https:\\\/\\\/adltexas.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adltexas\\\/\",\"https:\\\/\\\/x.com\\\/ADLofTX\",\"https:\\\/\\\/www.instagram.com\\\/animaldefenseleague\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/animal-defense-league\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/adoptADL\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jones - Liga de Defensa Animal de Texas - San Antonio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adltexas.org\/es\/mascotas\/jones-37463386\/","og_locale":"es_MX","og_type":"article","og_title":"Jones - Animal Defense League of Texas - San Antonio","og_description":"Hi there, my name is Jones, and I&#039;m a dog who has had a bit of a rough start. When people come to the shelter to visit, I tend to . . .","og_url":"https:\/\/adltexas.org\/es\/mascotas\/jones-37463386\/","og_site_name":"Animal Defense League of Texas - San Antonio","article_publisher":"https:\/\/www.facebook.com\/adltexas\/","article_modified_time":"2026-05-13T16:22:40+00:00","twitter_card":"summary_large_image","twitter_site":"@ADLofTX","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adltexas.org\/pets\/jones-37463386\/","url":"https:\/\/adltexas.org\/pets\/jones-37463386\/","name":"Jones - Liga de Defensa Animal de Texas - San Antonio","isPartOf":{"@id":"https:\/\/adltexas.org\/#website"},"datePublished":"2021-04-28T20:40:42+00:00","dateModified":"2026-05-13T16:22:40+00:00","breadcrumb":{"@id":"https:\/\/adltexas.org\/pets\/jones-37463386\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adltexas.org\/pets\/jones-37463386\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/adltexas.org\/pets\/jones-37463386\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adltexas.org\/"},{"@type":"ListItem","position":2,"name":"Pet Posts","item":"https:\/\/adltexas.org\/news\/pets\/"},{"@type":"ListItem","position":3,"name":"Jones"}]},{"@type":"WebSite","@id":"https:\/\/adltexas.org\/#website","url":"https:\/\/adltexas.org\/","name":"Liga de Defensa Animal de Texas - San Antonio","description":"Refugio para animales sin sacrificio, San Antonio, Texas","publisher":{"@id":"https:\/\/adltexas.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adltexas.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/adltexas.org\/#organization","name":"Liga de Defensa de los Animales de Texas","url":"https:\/\/adltexas.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/adltexas.org\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/adltexas.org\/wp-content\/uploads\/2016\/05\/adl-logo-ty.gif?fit=140%2C140&ssl=1","contentUrl":"https:\/\/i0.wp.com\/adltexas.org\/wp-content\/uploads\/2016\/05\/adl-logo-ty.gif?fit=140%2C140&ssl=1","width":140,"height":140,"caption":"Animal Defense League of Texas"},"image":{"@id":"https:\/\/adltexas.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adltexas\/","https:\/\/x.com\/ADLofTX","https:\/\/www.instagram.com\/animaldefenseleague\/","https:\/\/www.linkedin.com\/company\/animal-defense-league\/","https:\/\/www.youtube.com\/user\/adoptADL"]}]}},"_links":{"self":[{"href":"https:\/\/adltexas.org\/es\/wp-json\/wp\/v2\/pets\/204201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adltexas.org\/es\/wp-json\/wp\/v2\/pets"}],"about":[{"href":"https:\/\/adltexas.org\/es\/wp-json\/wp\/v2\/types\/pets"}],"version-history":[{"count":0,"href":"https:\/\/adltexas.org\/es\/wp-json\/wp\/v2\/pets\/204201\/revisions"}],"wp:attachment":[{"href":"https:\/\/adltexas.org\/es\/wp-json\/wp\/v2\/media?parent=204201"}],"wp:term":[{"taxonomy":"pet_categories","embeddable":true,"href":"https:\/\/adltexas.org\/es\/wp-json\/wp\/v2\/pet_categories?post=204201"},{"taxonomy":"cat_breeds","embeddable":true,"href":"https:\/\/adltexas.org\/es\/wp-json\/wp\/v2\/cat_breeds?post=204201"},{"taxonomy":"dog_breeds","embeddable":true,"href":"https:\/\/adltexas.org\/es\/wp-json\/wp\/v2\/dog_breeds?post=204201"},{"taxonomy":"pet_status","embeddable":true,"href":"https:\/\/adltexas.org\/es\/wp-json\/wp\/v2\/pet_status?post=204201"},{"taxonomy":"pet_age_filter","embeddable":true,"href":"https:\/\/adltexas.org\/es\/wp-json\/wp\/v2\/pet_age_filter?post=204201"},{"taxonomy":"pet_location","embeddable":true,"href":"https:\/\/adltexas.org\/es\/wp-json\/wp\/v2\/pet_location?post=204201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}